{"id":17088,"date":"2024-07-03T08:00:00","date_gmt":"2024-07-03T11:00:00","guid":{"rendered":"https:\/\/herospark.com\/blog\/?p=17088"},"modified":"2025-04-22T15:58:10","modified_gmt":"2025-04-22T18:58:10","slug":"o-que-e-razao-social-do-mei","status":"publish","type":"post","link":"https:\/\/herospark.com\/blog\/o-que-e-razao-social-do-mei\/","title":{"rendered":"O que \u00e9 raz\u00e3o social do MEI e onde encontrar? [Guia]"},"content":{"rendered":"\n<p>Voc\u00ea sabe o que \u00e9 raz\u00e3o social do MEI?<\/p>\n\n\n\n<p>Entrar no universo do empreendedorismo como um <a href=\"https:\/\/herospark.com\/blog\/faturamento-mei\/\">Microempreendedor Individual (MEI)<\/a> \u00e9 um passo importante e muitas vezes transformador na vida de muitos brasileiros.<\/p>\n\n\n\n<p>A modalidade, criada para formalizar a situa\u00e7\u00e3o de pequenos empres\u00e1rios, oferece uma s\u00e9rie de benef\u00edcios, como acesso a direitos previdenci\u00e1rios, emiss\u00e3o de nota fiscal e at\u00e9 mesmo cr\u00e9dito facilitado. <\/p>\n\n\n\n<p>No entanto, junto com as vantagens, surgem tamb\u00e9m d\u00favidas sobre conceitos e obriga\u00e7\u00f5es, entre eles, o que se destaca: a raz\u00e3o social do MEI. Mas afinal, o que \u00e9 raz\u00e3o social do MEI e onde encontrar essa informa\u00e7\u00e3o?<\/p>\n\n\n\n<p>Neste artigo, vamos nos aprofundar sobre a raz\u00e3o social, explicando sua import\u00e2ncia, como \u00e9 composta e, especialmente, onde voc\u00ea pode encontrar essa informa\u00e7\u00e3o crucial para o seu neg\u00f3cio. <\/p>\n\n\n\n<p>Acompanhe para esclarecer suas d\u00favidas e fortalecer ainda mais sua jornada como empreendedor.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_45_2 counter-hierarchy ez-toc-counter ez-toc-light-blue ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\">O que voc&ecirc; ver&aacute;:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"ez-toc-toggle-icon-1\"><label for=\"item-6a04d5086d52a\" aria-label=\"Table of Content\"><span style=\"display: flex;align-items: center;width: 35px;height: 30px;justify-content: center;direction:ltr;\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/label><input style='display:none' type=\"checkbox\" id=\"item-6a04d5086d52a\"><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/herospark.com\/blog\/o-que-e-razao-social-do-mei\/#A_importancia_da_razao_social_para_o_MEI\" title=\"A import\u00e2ncia da raz\u00e3o social para o MEI\">A import\u00e2ncia da raz\u00e3o social para o MEI<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/herospark.com\/blog\/o-que-e-razao-social-do-mei\/#Como_e_formada_a_razao_social_do_MEI\" title=\"Como \u00e9 formada a raz\u00e3o social do MEI?\">Como \u00e9 formada a raz\u00e3o social do MEI?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/herospark.com\/blog\/o-que-e-razao-social-do-mei\/#Onde_encontrar_a_razao_social_do_MEI\" title=\"Onde encontrar a raz\u00e3o social do MEI?\">Onde encontrar a raz\u00e3o social do MEI?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/herospark.com\/blog\/o-que-e-razao-social-do-mei\/#Perguntas_frequentes_sobre_a_razao_social_do_MEI\" title=\"Perguntas frequentes sobre a raz\u00e3o social do MEI\">Perguntas frequentes sobre a raz\u00e3o social do MEI<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/herospark.com\/blog\/o-que-e-razao-social-do-mei\/#Posso_alterar_a_razao_social_do_meu_MEI\" title=\"Posso alterar a raz\u00e3o social do meu MEI? \">Posso alterar a raz\u00e3o social do meu MEI? <\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/herospark.com\/blog\/o-que-e-razao-social-do-mei\/#O_que_fazer_se_a_razao_social_escolhida_ja_estiver_em_uso\" title=\"O que fazer se a raz\u00e3o social escolhida j\u00e1 estiver em uso? \">O que fazer se a raz\u00e3o social escolhida j\u00e1 estiver em uso? <\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/herospark.com\/blog\/o-que-e-razao-social-do-mei\/#A_razao_social_e_o_nome_fantasia_podem_ser_iguais\" title=\"A raz\u00e3o social e o nome fantasia podem ser iguais? \">A raz\u00e3o social e o nome fantasia podem ser iguais? <\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"A_importancia_da_razao_social_para_o_MEI\"><\/span>A import\u00e2ncia da raz\u00e3o social para o MEI<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para come\u00e7ar, entender a raz\u00e3o pela qual a raz\u00e3o social \u00e9 t\u00e3o crucial pode fazer toda a diferen\u00e7a na maneira como voc\u00ea gerencia seu neg\u00f3cio. <\/p>\n\n\n\n<p>Legalmente, \u00e9 este o nome que diferencia sua empresa de outras, sendo essencial para processos como abertura de conta banc\u00e1ria empresarial, emiss\u00e3o de notas fiscais e assinaturas de contratos. Sem ela, sua atua\u00e7\u00e3o se limita bastante, impedindo a expans\u00e3o e o reconhecimento de sua marca no mercado.<\/p>\n\n\n\n<p>Al\u00e9m disso, a raz\u00e3o social \u00e9 parte integral da identidade jur\u00eddica do seu neg\u00f3cio, atuando como um registro oficial do mesmo. \u00c9 ela que constar\u00e1 em todos os documentos legais, contratos e licen\u00e7as, configurando um elemento fundamental na estrutura\u00e7\u00e3o e formaliza\u00e7\u00e3o da sua empresa perante a lei.<\/p>\n\n\n\n<p>\u00c9 importante lembrar que, apesar de a raz\u00e3o social do MEI ser geralmente formada pelo nome do propriet\u00e1rio seguido de um c\u00f3digo (CNPJ) e o objeto social da empresa, o empreendedor tem uma margem de liberdade para escolher um nome que esteja alinhado com seus valores e objetivos de neg\u00f3cio, desde que respeite as normas e regulamenta\u00e7\u00f5es vigentes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_e_formada_a_razao_social_do_MEI\"><\/span>Como \u00e9 formada a raz\u00e3o social do MEI?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A composi\u00e7\u00e3o da raz\u00e3o social do MEI segue um padr\u00e3o estabelecido para garantir a unicidade e a formalidade necess\u00e1rias. Normalmente, ela inclui o nome completo do propriet\u00e1rio, seguido pela express\u00e3o MEI, e pode ou n\u00e3o incluir a atividade principal da empresa. <\/p>\n\n\n\n<p>A escolha deve ser feita com aten\u00e7\u00e3o, pois uma vez registrada, qualquer altera\u00e7\u00e3o na raz\u00e3o social implicar\u00e1 em um processo burocr\u00e1tico junto aos \u00f3rg\u00e3os respons\u00e1veis.<\/p>\n\n\n\n<p>Um aspecto interessante \u00e9 que, apesar da nomenclatura padr\u00e3o, o MEI tem a possibilidade de adicionar um nome fantasia durante o processo de cadastro. Esse nome fantasia \u00e9 como o neg\u00f3cio ser\u00e1 conhecido pelo p\u00fablico e pode ser diferente da raz\u00e3o social. <\/p>\n\n\n\n<p>Tal flexibilidade permite que o empreendedor crie uma marca mais atrativa e memor\u00e1vel para seus clientes, sem alterar a formalidade necess\u00e1ria nos tr\u00e2mites legais.<\/p>\n\n\n\n<p>Para assegurar que sua raz\u00e3o social seja \u00fanica e n\u00e3o cause confus\u00f5es com empresas j\u00e1 existentes, \u00e9 recomendado realizar uma pesquisa pr\u00e9via junto \u00e0 Junta Comercial da sua regi\u00e3o e no Portal do Empreendedor. Essa etapa \u00e9 essencial para evitar imprevistos e assegurar a exclusividade do nome escolhido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Onde_encontrar_a_razao_social_do_MEI\"><\/span>Onde encontrar a raz\u00e3o social do MEI?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Agora que voc\u00ea j\u00e1 sabe o que \u00e9 e qual a import\u00e2ncia da raz\u00e3o social do MEI, deve estar se perguntando onde encontr\u00e1-la. A boa not\u00edcia \u00e9 que acessar essa informa\u00e7\u00e3o \u00e9 mais simples do que parece. <\/p>\n\n\n\n<p>Inicialmente, ap\u00f3s a finaliza\u00e7\u00e3o do processo de registro do MEI, a raz\u00e3o social \u00e9 fornecida junto com o Certificado da Condi\u00e7\u00e3o de Microempreendedor Individual (CCMEI).<\/p>\n\n\n\n<p>Outro local onde voc\u00ea pode verificar a raz\u00e3o social do seu MEI \u00e9 atrav\u00e9s do Portal do Empreendedor, na se\u00e7\u00e3o de &#8220;Consulta de Situa\u00e7\u00e3o Cadastral&#8221;. <\/p>\n\n\n\n<p>Al\u00e9m disso, a raz\u00e3o social tamb\u00e9m aparece em documentos oficiais e fiscais da empresa, como notas fiscais e declara\u00e7\u00f5es anuais. Manter essas informa\u00e7\u00f5es \u00e0 m\u00e3o e em um local seguro \u00e9 fundamental para a gest\u00e3o eficaz do seu neg\u00f3cio.<\/p>\n\n\n\n<p>Entender que a raz\u00e3o social do seu MEI \u00e9 mais do que um mero detalhe burocr\u00e1tico, e sim uma parte integral da identidade e formalidade do seu neg\u00f3cio, \u00e9 o primeiro passo para uma jornada de sucesso. <\/p>\n\n\n\n<p>Certifique-se de que ela reflita o prop\u00f3sito e os valores do seu neg\u00f3cio, fortalecendo assim sua presen\u00e7a e reconhecimento no mercado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Perguntas_frequentes_sobre_a_razao_social_do_MEI\"><\/span>Perguntas frequentes sobre a raz\u00e3o social do MEI<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Posso_alterar_a_razao_social_do_meu_MEI\"><\/span>Posso alterar a raz\u00e3o social do meu MEI? <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Sim, \u00e9 poss\u00edvel, mas exige um processo junto \u00e0 Junta Comercial e outros \u00f3rg\u00e3os, al\u00e9m de poss\u00edveis taxas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_que_fazer_se_a_razao_social_escolhida_ja_estiver_em_uso\"><\/span>O que fazer se a raz\u00e3o social escolhida j\u00e1 estiver em uso? <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Voc\u00ea precisar\u00e1 escolher uma nova raz\u00e3o social que seja \u00fanica e n\u00e3o esteja registrada por outra empresa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"A_razao_social_e_o_nome_fantasia_podem_ser_iguais\"><\/span>A raz\u00e3o social e o nome fantasia podem ser iguais? <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Sim, podem ser iguais, mas \u00e9 mais comum que sejam diferentes para que o nome fantasia possa ser mais criativo e atrativo.<\/p>\n\n\n\n<p>Entender o que \u00e9 raz\u00e3o social do MEI e onde encontrar essa informa\u00e7\u00e3o \u00e9 um passo fundamental para a formaliza\u00e7\u00e3o e sucesso do seu neg\u00f3cio. A raz\u00e3o social n\u00e3o apenas confere legalidade ao seu empreendimento, mas tamb\u00e9m fortalece sua identidade no mercado. <\/p>\n\n\n\n<p>Lembre-se de que escolher uma raz\u00e3o social apropriada e \u00fanica \u00e9 essencial para evitar confus\u00f5es legais e assegurar a exclusividade do seu neg\u00f3cio.<\/p>\n\n\n\n<p>Ao seguir os passos corretos para o registro e manuten\u00e7\u00e3o do seu MEI, e ao manter-se informado sobre as obriga\u00e7\u00f5es e direitos que acompanham essa categoria empresarial, voc\u00ea estar\u00e1 bem posicionado para prosperar no mundo do empreendedorismo. A raz\u00e3o social \u00e9 apenas o come\u00e7o de uma jornada repleta de oportunidades e desafios. Boa sorte!<\/p>\n\n\n\n<p>Encontrou este artigo \u00fatil? Tem experi\u00eancias para compartilhar sobre a escolha da raz\u00e3o social do seu MEI? Deixe seu coment\u00e1rio abaixo ou confira outros artigos em nosso <a href=\"https:\/\/herospark.com\/blog\">blog<\/a> para mais dicas e informa\u00e7\u00f5es sobre empreendedorismo, infoprodutos, cursos online, e marketing digital.<\/p>\n","protected":false},"excerpt":{"rendered":"Voc&ecirc; sabe o que &eacute; raz&atilde;o social do MEI? Entrar no universo do empreendedorismo como um Microempreendedor Individual (MEI) &eacute; um passo importante e muitas vezes transformador na vida de&hellip;\n","protected":false},"author":63,"featured_media":17101,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[18,4309],"tags":[],"yst_prominent_words":[1148,1764,158,2109,2174,1146],"class_list":{"0":"post-17088","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-empreendedorismo","8":"category-legislacao-para-o-infoprodutor"},"acf":[],"uagb_featured_image_src":{"full":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa.jpg",1600,1067,false],"thumbnail":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-150x150.jpg",150,150,true],"medium":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-300x200.jpg",300,200,true],"medium_large":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-768x512.jpg",768,512,true],"large":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-1536x1024.jpg",1536,1024,true],"2048x2048":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa.jpg",1600,1067,false],"pk-small":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-80x80.jpg",80,80,true],"pk-thumbnail":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-300x225.jpg",300,225,true],"cs-small":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-80x80.jpg",80,80,true],"cs-intermediate":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-240x180.jpg",240,180,true],"cs-thumbnail":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-390x290.jpg",390,290,true],"cs-thumbnail-uncropped":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-390x260.jpg",390,260,true],"cs-medium":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-820x547.jpg",820,547,true],"cs-large":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-1180x787.jpg",1180,787,true],"web-stories-poster-portrait":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-640x853.jpg",640,853,true],"web-stories-publisher-logo":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-96x96.jpg",96,96,true],"web-stories-thumbnail":["https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa-150x100.jpg",150,100,true]},"uagb_author_info":{"display_name":"Nilson Filatieri","author_link":"https:\/\/herospark.com\/blog\/author\/nilson\/"},"uagb_comment_info":0,"uagb_excerpt":"Voc&ecirc; sabe o que &eacute; raz&atilde;o social do MEI? Entrar no universo do empreendedorismo como um Microempreendedor Individual (MEI) &eacute; um passo importante e muitas vezes transformador na vida de&hellip;","yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v14.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que \u00e9 raz\u00e3o social do MEI e onde encontrar? [Guia]<\/title>\n<meta name=\"description\" content=\"Neste artigo, vamos nos aprofundar sobre o que \u00e9 raz\u00e3o social do MEI, explicando sua import\u00e2ncia, como \u00e9 composta e onde voc\u00ea pode encontr\u00e1-la.\" \/>\n<meta name=\"robots\" content=\"index, follow\" \/>\n<meta name=\"googlebot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta name=\"bingbot\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/herospark.com\/blog\/o-que-e-razao-social-do-mei\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 raz\u00e3o social do MEI e onde encontrar? [Guia]\" \/>\n<meta property=\"og:description\" content=\"Neste artigo, vamos nos aprofundar sobre o que \u00e9 raz\u00e3o social do MEI, explicando sua import\u00e2ncia, como \u00e9 composta e onde voc\u00ea pode encontr\u00e1-la.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/herospark.com\/blog\/o-que-e-razao-social-do-mei\/\" \/>\n<meta property=\"og:site_name\" content=\"HeroSpark Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-03T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-22T18:58:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/herospark.com\/blog\/wp-content\/uploads\/sites\/6\/2024\/07\/46bom4lobsa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/herospark.com\/blog\/wp-json\/wp\/v2\/posts\/17088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/herospark.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/herospark.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/herospark.com\/blog\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/herospark.com\/blog\/wp-json\/wp\/v2\/comments?post=17088"}],"version-history":[{"count":0,"href":"https:\/\/herospark.com\/blog\/wp-json\/wp\/v2\/posts\/17088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/herospark.com\/blog\/wp-json\/wp\/v2\/media\/17101"}],"wp:attachment":[{"href":"https:\/\/herospark.com\/blog\/wp-json\/wp\/v2\/media?parent=17088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/herospark.com\/blog\/wp-json\/wp\/v2\/categories?post=17088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/herospark.com\/blog\/wp-json\/wp\/v2\/tags?post=17088"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/herospark.com\/blog\/wp-json\/wp\/v2\/yst_prominent_words?post=17088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}